{"id":301177,"date":"2023-07-25T10:59:45","date_gmt":"2023-07-25T08:59:45","guid":{"rendered":"https:\/\/mundomoneda.com\/?p=1232"},"modified":"2023-10-24T23:01:45","modified_gmt":"2023-10-24T21:01:45","slug":"monedas-romanas-antiguas","status":"publish","type":"post","link":"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/","title":{"rendered":"Mejores monedas romanas antiguas para coleccionar e invertir"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En este art\u00edculo puedes encontrar tanto informaci\u00f3n hist\u00f3rica valiosa sobre las monedas romanas antiguas, como un listado de las m\u00e1s buscadas y coleccionadas actualmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si te interesa \u00fanicamente el listado de las <strong><a href=\"https:\/\/mundomoneda.com\/romana\/monedas-romanas-antiguas\/#Estas_son_las_monedas_romanas_mas_valiosas_y_demandadas\" class=\"rank-math-link\" rel=\"nofollow noopener\" target=\"_blank\">monedas romanas m\u00e1s caras y buscadas haz click aqu\u00ed<\/a><\/strong> para ir directo a la secci\u00f3n correspondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cambio, si eres un entusiasta apasionado de la numism\u00e1tica puedes seguir leyendo, y encontrar\u00e1s informaci\u00f3n valiosa sobre la historia y evoluci\u00f3n de las monedas antiguas del imperio romano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comencemos por el principio.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#%C2%BFQue_tipos_de_monedas_romanas_existen\" >\u00bfQu\u00e9 tipos de monedas romanas existen?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#%C2%BFComo_identificar_las_monedas_romanas_autenticas\" >\u00bfC\u00f3mo identificar las monedas romanas aut\u00e9nticas?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#Estas_son_las_monedas_romanas_mas_valiosas_y_demandadas\" >Estas son las monedas romanas m\u00e1s valiosas y demandadas<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#Denarios_La_moneda_romana_de_referencia\" >Denarios: La moneda romana de referencia<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#%C2%BFCual_es_el_valor_de_un_denario_romano\" >\u00bfCu\u00e1l es el valor de un denario romano?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#Antoninianos_moneda_romana_misteriosa\" >Antoninianos: moneda romana misteriosa<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#%C2%BFCuanto_valen_las_monedas_romanas_antoninianos\" >\u00bfCu\u00e1nto valen las monedas romanas antoninianos?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#Sestercios_la_moneda_romana_de_bronce\" >Sestercios: la moneda romana de bronce<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#%C2%BFCual_es_el_precio_actual_de_un_Sestercio\" >\u00bfCu\u00e1l es el precio actual de un Sestercio?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#Aureo_Las_monedas_de_oro_para_coleccionistas_de_alto_nivel\" >\u00c1ureo: Las monedas de oro para coleccionistas de alto nivel &nbsp;<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#_%C2%BFCuanto_cuesta_un_Aureo_romano_en_la_actualidad\" >&nbsp;\u00bfCu\u00e1nto cuesta un \u00c1ureo romano en la actualidad?<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#%C2%BFCual_es_la_moneda_romana_mas_cara_jamas_vendida\" >\u00bfCu\u00e1l es la moneda romana m\u00e1s cara jam\u00e1s vendida?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/startup.info\/es\/monedas-romanas-antiguas\/#%C2%BFDonde_Comprar_monedas_romanas_valiosas\" >\u00bfD\u00f3nde Comprar monedas romanas valiosas?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_tipos_de_monedas_romanas_existen\"><\/span>\u00bfQu\u00e9 tipos de monedas romanas existen?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es dif\u00edcil responder con precisi\u00f3n a esta pregunta. Antes debemos tener claro que la historia de la numism\u00e1tica romana se extiende aproximadamente desde el 280 a.C. hasta la ca\u00edda del Imperio Romano en el 476 d.C.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las <strong>primeras monedas antiguas romanas son conocidas como As<\/strong>. Estas generalmente se conocen como <em>aes rude<\/em>, y son piezas muy r\u00fasticas y con apenas detalles, ya que eran fundidas y no acu\u00f1adas. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que decir que al principio era un poco ca\u00f3tico todo el tema de las monedas, ya que su valor estaba determinado por el peso. Por tanto, en el momento del intercambio deb\u00edan pesarse las piezas para saber cu\u00e1nto se estaba pagando en realidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por suerte, el <strong>rey Servio Tulio<\/strong> a mitad del siglo VI a. C. cre\u00f3 un sistema monetario verdadero, centrado en el <em>As Libral<\/em>, tambi\u00e9n denominado <em>aes grave<\/em>. El sistema estaba compuesto por el As, y otras 5 monedas fraccionarias. Estas ser\u00edan las primeras monedas romanas antiguas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El sistema monetario de monedas romanas basadas en el <strong>As<\/strong>, son:<\/p>\n\n\n<p>[su_table responsive=\u00bbyes\u00bb]<\/p>\n<table>\n<tbody>\n<tr>\n<th>Moneda<\/th>\n<th>Anverso<\/th>\n<th>Nombre<\/th>\n<th>Marca<\/th>\n<th>Peso Original<\/th>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/as.png\" alt=\"Moneda Romana As\" title=\"\"><\/td>\n<td>Jano<\/td>\n<td>As (1)<\/td>\n<td>I<\/td>\n<td>273g<\/td>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/semis.png\" alt=\"Moneda Romana Semis\" title=\"\"><\/td>\n<td>Saturno<\/td>\n<td>Semis (1\/2)<\/td>\n<td>S<\/td>\n<td>136,5g<\/td>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Triens.png\" alt=\"Moneda Romana Triens\" title=\"\"><\/td>\n<td>Minerva<\/td>\n<td>Triens (1\/3)<\/td>\n<td>cuatro puntos<\/td>\n<td>91g<\/td>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Quadrans.png\" alt=\"Moneda Romana Quadrans\" title=\"\"><\/td>\n<td>H\u00e9rcules<\/td>\n<td>Quadrans (1\/4)<\/td>\n<td>tres puntos<\/td>\n<td>68,25g<\/td>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Sextans.png\" alt=\"Moneda Romana Sextans\" title=\"\"><\/td>\n<td>Minerva<\/td>\n<td>Sextans (1\/6)<\/td>\n<td>dos puntos<\/td>\n<td>45,5g<\/td>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Uncia.png\" alt=\"Moneda Romana Uncia\" title=\"\"><\/td>\n<td>Bellona<\/td>\n<td>Uncia (1\/12)<\/td>\n<td>un punto<\/td>\n<td>22,75g<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/su_table]<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como puedes comprobar en la tabla anterior, el As fue sufriendo constantes depreciaciones, que llevaron a que en etapas posteriores se acu\u00f1aran otras monedas m\u00e1s fuertes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, los dos periodos m\u00e1s importantes, en lo que a <strong>acu\u00f1aci\u00f3n de monedas romanas<\/strong> respecta, son la <strong>\u00c9poca Republicana<\/strong> y la <strong>\u00c9poca de Augusto<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Denario-Gens-Marcia.jpg\" alt=\"Denario Gens Marcia\" class=\"wp-image-1243\" title=\"\"><figcaption><em><strong>Denario Gens Marcia<\/strong><\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">En la \u00c9poca Republicana la moneda oficial romana es el <em><strong>denario argentum<\/strong><\/em>, que muchos especialistas consideran una r\u00e9plica de <strong>Dracma Griego<\/strong>. El Denario, al igual que ocurri\u00f3 con otros sistemas monetarios romanos, contaba con una pieza unitaria y varias piezas fraccionarias de la misma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De hecho, en este periodo, el As no se desaparece, sino que es considerada una d\u00e9cima parte del denario. En otras palabras, <strong>10 As equival\u00edan a 1 Denario<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las monedas romanas antiguas de la \u00c9poca Republicana, y su equivalencia con los denarios, son:<\/p>\n\n\n<p>[su_list icon=\u00bbicon: check-circle\u00bb icon_color=\u00bb#d3570b\u00bb]<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Denario<\/strong> = <strong>Unidad monetaria<\/strong><\/li><li><strong>4 Sestercio<\/strong> = 1 Denario<\/li><li><strong>5 Dupondio<\/strong> = 1 Denario<\/li><li><strong>10 As<\/strong> = 1 Denario<\/li><li><strong>20 Semis<\/strong> = 1 Denario<\/li><li><strong>30 Triens<\/strong> = 1 Denario<\/li><li><strong>40 Quadrans<\/strong> = 1 Denario<\/li><li><strong>24 Quincunx<\/strong> = 1 Denario<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_list]<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eventualmente el denario tambi\u00e9n perdi\u00f3 valor, debido a la inflaci\u00f3n y se crean nuevas monedas romanas de mayor denominaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un ejemplo de esto es la moneda romana <strong>\u00c1ureo<\/strong>, equivalente a 10 o 25 denarios, seg\u00fan la fecha que se tome como referencia. Tambi\u00e9n podemos mencionar el <strong>Quinario \u00c1ureo<\/strong>, con un valor correspondiente a la mitad de un <strong>\u00c1ureo<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Quinario-Octavio-Augusto.jpg\" alt=\"Moneda romana Quinario Octavio Augusto\" class=\"wp-image-1233\" title=\"\"><figcaption><em><strong>Quinario Octavio Augusto<\/strong><\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Aureo-Octavio-Augusto.jpg\" alt=\"Moneda romana Aureo Octavio Augusto\" class=\"wp-image-1235\" title=\"\"><figcaption><em><strong>Aureo Octavio Augusto<\/strong><\/em><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00c1ureo fue sustituido en el <strong>S\u00f3lido<\/strong>, por el emperador <strong>Constantino I el Grande<\/strong>. El S\u00f3lido, S\u00f3lido bizantino, o S\u00f3lido \u00c1ureo, por sus distintas denominaciones, fue una moneda romana acu\u00f1ada en oro muy valorada por su pureza y peso siempre estables.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Constantino-I-Nicomedia-Solido.jpg\" alt=\"Moneda romana  Solido Constantino I Nicomedia\" class=\"wp-image-1237\" title=\"\"><figcaption><em><strong> Solido Constantino I Nicomedia<\/strong><\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">El S\u00f3lido alcanz\u00f3 un valor aproximado de 1000 a 2000 denarios, seg\u00fan la fecha que se tome como referencia. Fue la moneda romana m\u00e1s com\u00fan en el periodo de conocido como <strong>Bajo Imperio Romano<\/strong>, y es actualmente una de las preferidas por coleccionistas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_identificar_las_monedas_romanas_autenticas\"><\/span>\u00bfC\u00f3mo identificar las monedas romanas aut\u00e9nticas?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para identificar las monedas romanas aut\u00e9nticas siempre es mejor contar con la opini\u00f3n de un especialista numism\u00e1tico. Sin embargo, algunos elementos comunes en las monedas de este periodo y geograf\u00eda te ayudar\u00e1n a reconocer r\u00e1pido si est\u00e1s, o no, en presencia de una moneda romana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de <strong>las monedas romanas antiguas tienen en una de sus caras el busto del emperador<\/strong> que reg\u00eda en el momento que fueron acu\u00f1adas. Si logras reconocer quien est\u00e1 representado, ya podr\u00edas ubicar el periodo en que se puso en circulaci\u00f3n la pieza en cuesti\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos coleccionistas llegan incluso a centrarse en reunir la mayor cantidad de monedas del mismo emperador romano. Otros intentan crear una colecci\u00f3n en la que est\u00e9n representados los distintos jerarcas del imperio romano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro elemento importante en las monedas romanas es que sus <strong>leyendas est\u00e1n escritas en lat\u00edn<\/strong>. Las diferentes frases, ya sea en el anverso o reverso, ser\u00e1n de gran ayuda para reconocer la moneda en cuesti\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n muchas monedas romanas presentan la inscripci\u00f3n <strong>CS<\/strong>.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Livia-Roma-Dupondio.jpg\" alt=\"Moneda Romana Livia Roma Dupondio\" class=\"wp-image-1238\" title=\"\"><figcaption><strong><em>Livia Roma Dupondio<\/em><\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 significa CS en las monedas romanas?<\/strong> Estas siglas representan las palabras <em><strong>\u201cSenatus Consulto\u201d<\/strong><\/em>, y significan que esa pieza contaba con el reconocimiento y apoyo del senado romano. Es v\u00e1lido destacar que algunas piezas no tienen las siglas, y aun as\u00ed se consideran aut\u00e9nticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tienes una moneda antigua, y crees que pudiera ser una moneda antigua romana, el primer paso es contrastarla con alg\u00fan cat\u00e1logo en l\u00ednea; o mejor, consultar un especialista que pueda certificar la autenticidad de la pieza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es posible que no lo sepas, pero existen muchas falsificaciones de monedas romanas antiguas, ya que son m\u00e1s f\u00e1ciles de recrear que las monedas modernas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Estas_son_las_monedas_romanas_mas_valiosas_y_demandadas\"><\/span>Estas son las monedas romanas m\u00e1s valiosas y demandadas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora que ya tienes cierto conocimiento numism\u00e1tico de la antigua Roma, revisemos cu\u00e1les son las monedas romanas m\u00e1s interesantes para coleccionar e invertir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Denarios_La_moneda_romana_de_referencia\"><\/span>Denarios: La moneda romana de referencia<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los <strong>denarios son muy populares entre los coleccionistas de monedas romanas<\/strong>, ya que por mucho tiempo fue el eje del sistema monetario del Imperio Romano. Muchos de los denarios conocidos fueron acu\u00f1ados en Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debemos reconocer que la preferencia de los coleccionistas por los denarios tambi\u00e9n est\u00e1 motivada por la gran popularidad y demanda de estas piezas. Otras denominaciones no son tan conocidas como los Denarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas piezas de Denario incluyen alguna de sus caras, bustos de deidades o emperadores, lo que les confiere un gran atractivo para los coleccionistas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCual_es_el_valor_de_un_denario_romano\"><\/span>\u00bfCu\u00e1l es el valor de un denario romano?<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La realidad es que los precios de <strong>los denarios romanos son muy variables<\/strong> y depende de varios factores diferentes: fecha de acu\u00f1aci\u00f3n, disponibilidad de otros ejemplares, demanda de los coleccionistas, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los precios pueden ir desde unos pocos cientos de euros o d\u00f3lares, hasta varios miles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Te comparto algunos Denarios subastados en <strong>Aureo &amp; Calic\u00f3<\/strong> y sus precios de adjudicaci\u00f3n:<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bbDenario con bustos de Marco Aurelio y C\u00f3modo\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Denario-con-bustos-de-Marco-Aurelio-y-Comodo.jpg\" alt=\"Denario con bustos de Marco Aurelio y C\u00f3modo\" class=\"wp-image-1269\" title=\"\"><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Esta es una hermosa moneda romana de plata, datada en 175 a.C. y con un peso de 3.28 grs. Fue subastada en 2012 por: 8500 euros. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bbDenario con busto de Faustina y posiblemente figura de Galia de pie\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Denario-con-busto-de-Faustina-y-posiblemente-figura-de-Galia-de-pie.jpg\" alt=\"Denario con busto de Faustina y posiblemente figura de Galia de pie\" class=\"wp-image-1270\" title=\"\"><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Este denario romano de plata, datada entre 161 y 176 d.C. tiene un peso de 3.57 grs. Esta catalogada como una pieza \u201cmuy bella\u201d. Fue subastada en 2012 por: 1000 euros. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bbDenario con busto de Didia Clara\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Denario-con-busto-de-Didia-Clara.jpg\" alt=\"Denario con busto de Didia Clara\" class=\"wp-image-1282\" title=\"\"><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Este Denario de plata, datado en 193 d.C. tiene un peso de 2.52 grs, es una moneda excepcionalmente bella. Fue subastada en 2012 por: 3800 euros. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bbDenario con busto de Didio Juliano\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Denario-con-busto-de-Didio-Juliano.jpg\" alt=\"Denario con busto de Didio Juliano\" class=\"wp-image-1285\" title=\"\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Este Denario de plata, datado en 193 d.C. tiene un peso de 2.83 grs, es una moneda antigua romana catalogada como Muy Bella y Rara. Fue subastada en 2012 por: 10,000 euros. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Antoninianos_moneda_romana_misteriosa\"><\/span>Antoninianos: moneda romana misteriosa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se conoce como Antoninianos a las monedas romanas antiguas acu\u00f1adas en el Siglo III, de las cuales se ignora el nombre real en la \u00e9poca. Estas monedas, acu\u00f1adas originalmente en plata, eran equivalentes a 2 Denarios, aunque los especialistas dicen que nunca llego a valer m\u00e1s que 1.6 Denarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los antoninianos sufrieron sucesivas devaluaciones que obligaron a que se terminaran acu\u00f1ando en bronce. Por esto, los coleccionistas de monedas pueden tener piezas en ambos metales, igualmente aut\u00e9nticas, seg\u00fan el periodo en que se fabricaron.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCuanto_valen_las_monedas_romanas_antoninianos\"><\/span>\u00bfCu\u00e1nto valen las monedas romanas antoninianos?<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Los antoninianos o dobles denarios, se puede conseguir a partir de unas cuentas decenas de d\u00f3lares y dif\u00edcilmente alg\u00fan coleccionista est\u00e9 dispuesto a pagar m\u00e1s de 200 d\u00f3lares por uno. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Antoninianos-de-Pacatianus-1.jpg\" alt=\"Moneda Romana Antoninianos de Pacatianus\" class=\"wp-image-1241\" title=\"\"><figcaption><em><strong>Antoninianos de Pacatianus<\/strong><\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Solo el Antoniniano de Pacatianus, supuestamente puede alcanzar el valor de varios miles de d\u00f3lares.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sestercios_la_moneda_romana_de_bronce\"><\/span>Sestercios: la moneda romana de bronce <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Entramos nuevamente en las monedas romanas mejor valorada por los coleccionistas. Los sestercios, acu\u00f1ados en plata, son a la vez impactantes y accesibles para quienes se adentran en el mundo del coleccionismo de monedas antiguas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mayor\u00eda son monedas romanas muy bonitas en la que se aprecian los bustos de emperadores de una forma muy visual. Los Sestercios muy buscados son: <\/p>\n\n\n<p>[su_list icon=\u00bbicon: check-circle\u00bb icon_color=\u00bb#d3570b\u00bb]<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Sestercios de Marco Aurelio, <\/strong><\/li><li><strong>Sestercio de Trajano, <\/strong><\/li><li><strong>Sestercio de Claudio y<\/strong><\/li><li><strong>Sestercio de Alejandro Severo<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_list]<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCual_es_el_precio_actual_de_un_Sestercio\"><\/span>\u00bfCu\u00e1l es el precio actual de un Sestercio?<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">En buena calidad, se pueden encontrar a partir de los 100 d\u00f3lares, pero algunos ejemplares superan los miles de d\u00f3lares en las subastas numism\u00e1ticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora revisemos algunas piezas subastadas y sus precios.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bbSestercio con busto de Julia Paula\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Sestercio-con-busto-de-Julia-Paula.jpg\" alt=\"Sestercio con busto de Julia Paula\" class=\"wp-image-1291\" title=\"\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosa moneda romana, datada en 220 d.C. y con un peso de 18.63 grs. Aun con los campos levemente reparados, fue subastada en 2012 por: 7500 euros. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bbSestercio con busto de Claudio\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Sestercio-con-busto-de-Claudio.jpg\" alt=\"Sestercio con busto de Claudio\" class=\"wp-image-1292\" title=\"\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Este Sestercio se encuentra datado entre 37 y 38 a.C. y con un peso de 28.55 grs. La pieza fue subastada en 2012 por: 5000 euros. \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bbSestercio con busto de Mariniana\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Sestercio-con-busto-de-Mariniana.jpg\" alt=\"Sestercio con busto de Mariniana\" class=\"wp-image-1296\" title=\"\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sestercio romano, datado entre los a\u00f1os 253 y 254 d.C., con un peso de 22.68 grs. Considerada una pieza bella y rara, fue subastada en 2012 por: 12000 euros. \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bbSestercio con busto de Trajano\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Sestercio-con-busto-de-Trajano.jpg\" alt=\"Sestercio con busto de Trajano\" class=\"wp-image-1297\" title=\"\"><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Este famoso Sestercio, datado entre 103 y 111 d.C., tiene un peso de 28.49 grs. Es una moneda romana Bella y Escasa que fue subastada en 2012 por: 14000 euros.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Aureo_Las_monedas_de_oro_para_coleccionistas_de_alto_nivel\"><\/span>\u00c1ureo: Las monedas de oro para coleccionistas de alto nivel &nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando se habla de coleccionar monedas romanas de oro, los \u00c1ureos se llevan el lugar de honor. De hecho, es una de las monedas antiguas de oro m\u00e1s apreciadas por coleccionistas y numism\u00e1ticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar que <strong>los \u00c1ureos tienen el mismo tama\u00f1o que los denarios<\/strong>, tanto en su tiempo como en la actualidad, el valor de estos superar a aquellos de forma considerable. <strong>Comprar un \u00c1ureo es siempre una buena decisi\u00f3n<\/strong>, ya sea como forma de inversi\u00f3n o simplemente para coleccionarlo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"_%C2%BFCuanto_cuesta_un_Aureo_romano_en_la_actualidad\"><\/span>&nbsp;\u00bfCu\u00e1nto cuesta un \u00c1ureo romano en la actualidad?<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9eme cuando te digo que el precio de un \u00c1ureo romano puede sorprenderte mucho, pues son piezas con mucho valor y bien pagadas. Yo dir\u00eda que se encuentran, con mucha seguridad, entre las monedas romanas m\u00e1s caras del mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, te muestro algunos \u00c1ureos subastados y sus precios:<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bb\u00c1ureo con busto de Octavio Augusto\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Aureo-con-busto-de-Octavio-Augusto.jpg\" alt=\"\u00c1ureo con busto de Octavio Augusto\" class=\"wp-image-1301\" title=\"\"><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Este \u00c1ureo de Octavio, datado entre el 25 y el 22 a.C. tiene un peso de 7.73 grs. Es una pieza considerada rara y en buen estado de conservaci\u00f3n. Fue subastada en 2012 por: 45000 euros.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bb\u00c1ureo con busto de Octavio Augusto\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Otro-Aureo-con-busto-de-Octavio-Augusto.jpg\" alt=\"\u00c1ureo con busto de Octavio Augusto\" class=\"wp-image-1303\" title=\"\"><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Este otro \u00c1ureo de oro, datado entre el 32 y el 31 a.C. tiene un peso de 7.66 grs. Es una moneda simple pero hermosa Fue subastada en 2012 por: 50000 euros.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bb\u00c1ureo con bustos de Tiberio y Augusto\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Aureo-con-bustos-de-Tiberio-y-Augusto.jpg\" alt=\"\u00c1ureo con bustos de Tiberio y Augusto\" class=\"wp-image-1304\" title=\"\"><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Este \u00c1ureo de oro, datado entre el 14 y 16 d.C. tiene un peso de 7.79 grs. Es una moneda muy rara y muy bella seg\u00fan el cat\u00e1logo. Fue subastada en 2012 por: 60,000 euros.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>[su_box title=\u00bb\u00c1ureo con busto de Sexto Pompeyo\u00bb box_color=\u00bb#000000&#8243; title_color=\u00bb#fff45e\u00bb]<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Aureo-con-busto-de-Sexto-Pompeyo.jpg\" alt=\"\u00c1ureo con busto de Sexto Pompeyo\" class=\"wp-image-1305\" title=\"\"><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Esta es una hermosa moneda romana de oro, datada en 42 a.C. y con un peso de 7.95 grs. La pieza con muchos detalles atractivos, fue subastada en 2012 por: 170,000 euros.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[\/su_box]&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCual_es_la_moneda_romana_mas_cara_jamas_vendida\"><\/span>\u00bfCu\u00e1l es la moneda romana m\u00e1s cara jam\u00e1s vendida?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La moneda romana m\u00e1s cara que se ha vendido o subastado hasta la fecha es un <strong>Sestercio del Emperador Adriano<\/strong>, que alcanz\u00f3 el valor de 2 millones de d\u00f3lares.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/mundomoneda.com\/wp-content\/uploads\/2021\/05\/Sestercio-del-Emperador-Adriano.jpg\" alt=\"Moneda romana Sestercio del Emperador Adriano\" class=\"wp-image-1239\" title=\"\"><figcaption><em><strong>Sestercio del Emperador Adriano<\/strong><\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La moneda romana mencionada fue subastada por la casa suiza Numism\u00e1tica Genevensis, en diciembre de 2008.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por supuesto, la pieza subastada por <strong><a href=\"https:\/\/www.ngsa.ch\/\" target=\"_blank\" aria-label=\"Numismatica Genevensis (opens in a new tab)\" rel=\"noreferrer noopener nofollow\" class=\"rank-math-link\">Numismatica Genevensis<\/a><\/strong> es uno de los ejemplares de la \u00e9poca romana mejor conservados, entre los sestercios conocidos. Y debemos considerar que los sestercios imperiales tipo medalla, se encuentran entre las m\u00e1s monedas romanas m\u00e1s codiciadas por su inusual calidad art\u00edstica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un dato curioso es que muchos de <strong>los Sestercios son atribuidos al trabajo de un solo grabador<\/strong>, conocido en entre los numism\u00e1ticos y coleccionistas como el <strong>\u201cMaestro Alfeo\u00bb<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se especula que el <strong>grabador de las monedas romanas antiguas m\u00e1s caras<\/strong> jam\u00e1s vendida podr\u00eda ser el escultor Antoniano de Afrodisias, por su estilo del clasicismo griego impulsado por Adriano. Lamentablemente esto es solo una conjetura, y no se ha podido demostrar de forma contundente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFDonde_Comprar_monedas_romanas_valiosas\"><\/span>\u00bfD\u00f3nde Comprar monedas romanas valiosas?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para concluir este art\u00edculo, repasemos los sitios m\u00e1s comunes donde puedes comprar o vender monedas romanas, siempre que sean atenticas y tengan gran valor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciertamente, este tipo de monedas no puedes encontrarlas en mercados populares, ni en casas de subasta de barrio. Las monedas antiguas de Roma, generalmente est\u00e1n en manos de coleccionistas o vendedores de m\u00e1s alto nivel. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces, si te interesa comprar monedas de colecci\u00f3n romanas, te recomiendo averiguar <strong>cu\u00e1les son las casas de subastas o numism\u00e1ticas<\/strong> existentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, puedes acceder a subastas online, aunque en este caso, recomiendo que te asegures sobre la historia del sitio. Si es un sitio seguro, si existen opiniones acertadas sobre el mismo, cu\u00e1ntas subastas han realizado y cu\u00e1les son los resultados de las mismas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En pr\u00f3ximos art\u00edculos voy a estar profundizando sobre este tema, as\u00ed que mantente revisando el blog, ya que se vienen muchas novedades pronto.<\/p>\n\n\n\n<script type=\"application\/ld+json\">{\"@context\":\"https:\/\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"\u00bfQu\u00e9 tipos de monedas romanas existen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Existen muchos tipos de monedas romanas antiguas, sin embargo, las m\u00e1s conocidas y buscadas por coleccionistas son los Denarios, Sestercios, Antoninianos, los \u00c1ureo y los S\u00f3lidos.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfC\u00f3mo identificar las monedas romanas aut\u00e9nticas?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Para identificar las monedas romanas aut\u00e9nticas siempre es mejor contar con la opini\u00f3n de un especialista numism\u00e1tico. Sin embargo, algunos elementos comunes en las monedas de este periodo y geograf\u00eda te ayudar\u00e1n a reconocer r\u00e1pido si est\u00e1s, o no, en presencia de una moneda romana.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfCu\u00e1l es el valor de un denario romano?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Los precios de los denarios romanos son muy variables y depende de varios factores diferentes: fecha de acu\u00f1aci\u00f3n, disponibilidad de otros ejemplares, demanda de los coleccionistas, entre otros.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfCu\u00e1nto valen las monedas romanas antoninianos?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Los antoninianos o dobles denarios, se puede conseguir a partir de unas cuentas decenas de d\u00f3lares y dif\u00edcilmente alg\u00fan coleccionista est\u00e9 dispuesto a pagar m\u00e1s de 200 d\u00f3lares por uno.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfCu\u00e1l es el precio actual de un Sestercio?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"En buena calidad, los Sestercios se pueden encontrar a partir de los 100 d\u00f3lares, pero algunos ejemplares superan los miles de d\u00f3lares en las subastas numism\u00e1ticas.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfCu\u00e1nto cuesta un \u00c1ureo romano en la actualidad?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"El precio de un \u00c1ureo romano puede sorprenderte mucho, pues son piezas con mucho valor y bien pagadas. Yo dir\u00eda que se encuentran, con mucha seguridad, entre las monedas romanas m\u00e1s caras del mundo.\"}},{\"@type\":\"Question\",\"name\":\"\u00bfCu\u00e1l es la moneda romana m\u00e1s cara jam\u00e1s vendida?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"La moneda romana m\u00e1s cara que se ha vendido o subastado hasta la fecha es un Sestercio del Emperador Adriano, que alcanz\u00f3 el valor de 2 millones de d\u00f3lares.\"}}]}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Algunas de estas monedas romanas pueden llegar a costar cientos de miles de d\u00f3lares. Te vas a sorprender seguro.<\/p>\n","protected":false},"author":39209,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[24903,24904],"tags":[],"class_list":["post-301177","post","type-post","status-publish","format-standard","hentry","category-news-es","category-recursos"],"_links":{"self":[{"href":"https:\/\/startup.info\/es\/wp-json\/wp\/v2\/posts\/301177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/startup.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startup.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startup.info\/es\/wp-json\/wp\/v2\/users\/39209"}],"replies":[{"embeddable":true,"href":"https:\/\/startup.info\/es\/wp-json\/wp\/v2\/comments?post=301177"}],"version-history":[{"count":0,"href":"https:\/\/startup.info\/es\/wp-json\/wp\/v2\/posts\/301177\/revisions"}],"wp:attachment":[{"href":"https:\/\/startup.info\/es\/wp-json\/wp\/v2\/media?parent=301177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startup.info\/es\/wp-json\/wp\/v2\/categories?post=301177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startup.info\/es\/wp-json\/wp\/v2\/tags?post=301177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}