{"id":181244,"date":"2021-06-03T14:25:05","date_gmt":"2021-06-03T12:25:05","guid":{"rendered":"https:\/\/startup.info\/?p=181244"},"modified":"2024-08-02T09:38:18","modified_gmt":"2024-08-02T14:38:18","slug":"comment-faire-pour-economiser-lenergie-dans-votre-entreprise","status":"publish","type":"post","link":"https:\/\/startup.info\/fr\/comment-faire-pour-economiser-lenergie-dans-votre-entreprise\/","title":{"rendered":"Comment faire pour \u00e9conomiser l&rsquo;\u00e9nergie dans votre entreprise ?"},"content":{"rendered":"<p style=\"padding-left: 40px;\"><em><strong>Les recommandations pour \u00e9conomiser l\u2019\u00e9nergie dans votre entreprise peuvent \u00eatre divis\u00e9es en quatre domaines : le chauffage, l&rsquo;\u00e9clairage, la climatisation et les \u00e9quipements de bureau. \u00c0 partir de ces quatre domaines, vous pouvez mettre en \u0153uvre une s\u00e9rie de mesures qui vous aideront \u00e0 minimiser la consommation d\u2019\u00e9nergie et l&rsquo;impact environnemental de votre activit\u00e9. <\/strong><\/em><\/p>\n<p>Afin d&rsquo;identifier vos pistes d&rsquo;am\u00e9lioration, il existe des \u00a0initiatives que vous pouvez mettre en \u0153uvre, par exemple, un audit environnemental ou \u00e9nerg\u00e9tique qui r\u00e9v\u00e8le les domaines dans lesquels vous pouvez \u00e9conomiser davantage d&rsquo;\u00e9nergie.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/startup.info\/fr\/comment-faire-pour-economiser-lenergie-dans-votre-entreprise\/#Economiser_lenergie_avec_leclairage_des_bureaux\" >\u00c9conomiser l&rsquo;\u00e9nergie avec l&rsquo;\u00e9clairage des bureaux<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/startup.info\/fr\/comment-faire-pour-economiser-lenergie-dans-votre-entreprise\/#Economiser_lenergie_dans_la_climatisation_et_le_chauffage_des_bureaux\" >\u00c9conomiser l&rsquo;\u00e9nergie dans la climatisation et le chauffage des bureaux<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/startup.info\/fr\/comment-faire-pour-economiser-lenergie-dans-votre-entreprise\/#Equipement_de_bureau_et_economie_denergie\" >Equipement de bureau et \u00e9conomie d&rsquo;\u00e9nergie<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Economiser_lenergie_avec_leclairage_des_bureaux\"><\/span>\u00c9conomiser l&rsquo;\u00e9nergie avec l&rsquo;\u00e9clairage des bureaux<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En fonction de votre secteur d&rsquo;activit\u00e9, l&rsquo;\u00e9clairage de votre bureau ou de vos locaux professionnels peut repr\u00e9senter une consommation d\u2019\u00e9nergie qui n&rsquo;est pas n\u00e9gligeable (en moyenne 5%)\u00a0. Des aides CEE avantageuses sont disponibles pour vous aider \u00e0 diminuer votre consommation sur ce poste. Il s\u2019agit d\u2019un bon endroit pour commencer \u00e0 \u00e9conomiser. L&rsquo;une des mesures les plus simples que vous pouvez prendre est de changer les ampoules pour des ampoules LED . Mais vous ne devez pas seulement regarder les ampoules, vous pouvez aussi rechercher des lampes efficaces, qui maximisent la lumi\u00e8re \u00e9manant de l&rsquo;ampoule. Vous pouvez par exemple opter pour des r\u00e9gulateurs de flux lumineux qui vous permettent de n&rsquo;utiliser que la puissance n\u00e9cessaire. De plus, si vous le pouvez, profitez de l&rsquo;\u00e9clairage naturel. En effet, en plus d\u2019\u00e9conomiser l\u2019\u00e9nergie, il r\u00e9duit la fatigue oculaire des travailleurs. La lumi\u00e8re naturelle et artificielle peuvent \u00eatre parfaitement combin\u00e9es. Les travailleurs doivent \u00e9galement prendre part \u00e0 ces initiatives d&rsquo;<a href=\"https:\/\/pro.engie.fr\/economies-d-energie\/comment-faire-des-economies-d-energie\/adopter-les-bonnes-pratiques\/4-reflexes-pour-economiser-de-l-energie-en-tpe\" rel=\"follow nofollow noopener\" target=\"_blank\">\u00e9conomies \u00e9nergies dans les TPE et PME<\/a>, et c&rsquo;est \u00e0 eux d&rsquo;\u00e9teindre les lumi\u00e8res lorsqu&rsquo;elles ne sont pas n\u00e9cessaires. C&rsquo;est \u00e0 vous de leur en faire prendre conscience.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Economiser_lenergie_dans_la_climatisation_et_le_chauffage_des_bureaux\"><\/span>\u00c9conomiser l&rsquo;\u00e9nergie dans la climatisation et le chauffage des bureaux<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Dans un but d\u2019\u00e9conomie d\u2019\u00e9nergie, en \u00e9t\u00e9 la climatisation doit \u00eatre r\u00e9gl\u00e9e \u00e0 4 \u2103 sous la temp\u00e9rature ext\u00e9rieure et sans descendre sous les 26 \u2103, selon les recommandations de l\u2019ADEME, pour \u00e9viter tout choc thermique. Et en hiver, la temp\u00e9rature optimale pour travailler est\u00a0 de 20\u00baC. Vous pouvez r\u00e9gler la climatisation du bureau pour qu&rsquo;il soit toujours \u00e0 cette temp\u00e9rature, \u00e9vitant ainsi une utilisation inutile d&rsquo;\u00e9nergie. Pour tirer le meilleur parti de ces appareils, v\u00e9rifiez-les r\u00e9guli\u00e8rement. Il faut \u00e9galement profiter de la lumi\u00e8re du soleil : en hiver, elle vous r\u00e9chauffe, mais en \u00e9t\u00e9, vous pouvez utiliser des outils tels que des stores pour emp\u00eacher la chaleur d\u2019entrer en exc\u00e8s dans le bureau, sans perdre cette lumi\u00e8re naturelle.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Equipement_de_bureau_et_economie_denergie\"><\/span>Equipement de bureau et \u00e9conomie d&rsquo;\u00e9nergie<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Encore une fois, le secteur dans lequel vous travaillez est la cl\u00e9 pour mesurer les \u00e9conomies d\u2019\u00e9nergie apport\u00e9es. Par exemple, s&rsquo;il n&rsquo;y a pas d&rsquo;\u00e9quipe de nuit ou de week-end, \u00e9teindre les imprimantes et les photocopieuses la nuit et le week-end peut permettre de diminuer de 10% leur consommation. Le modem ou le routeur repr\u00e9sentent \u00e9galement une d\u00e9pense importante lorsque personne ne les utilise, et c&rsquo;est \u00e0 vous de les d\u00e9connecter.<\/p>\n<p>Enfin, vous avez les ordinateurs, qui peuvent repr\u00e9senter jusqu\u2019\u00e0 8% de la <a href=\"https:\/\/pro.engie.fr\/economies-d-energie\/comment-faire-des-economies-d-energie\/reduire-sa-consommation-par-equipements\/pourquoi-faire-des-economies-d-energies-en-start-ups-et-bureaux\" rel=\"follow nofollow noopener\" target=\"_blank\">consommation d\u2019\u00e9lectricit\u00e9 en entreprise<\/a>. Pour commencer, r\u00e9glez vos ordinateurs en mode d&rsquo;\u00e9conomie d&rsquo;\u00e9nergie afin de limiter la consommation d&rsquo;\u00e9nergie. Lorsque vous allez faire des pauses de plus d&rsquo;une heure, vous pouvez les \u00e9teindre ou au moins les mettre en veille. Pour les pauses plus courtes, en plus de la mise en veille, \u00e9teignez l&rsquo;\u00e9cran. Vous devriez faire cela \u00e0 chaque fois que vous \u00e9teignez le PC.<\/p>\n<p>Maintenant vous savez comment \u00e9conomiser l&rsquo;\u00e9nergie. C&rsquo;est donc le meilleur moyen d&rsquo;impliquer votre entreprise dans une d\u00e9marche \u00e9cologique tout en r\u00e9duisant vos factures !<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les recommandations pour \u00e9conomiser l\u2019\u00e9nergie dans votre entreprise peuvent \u00eatre divis\u00e9es en quatre domaines : le chauffage, l&rsquo;\u00e9clairage, la climatisation et les \u00e9quipements de bureau. \u00c0 partir de ces quatre domaines, vous pouvez mettre en \u0153uvre une s\u00e9rie de mesures qui vous aideront \u00e0 minimiser la consommation d\u2019\u00e9nergie et l&rsquo;impact environnemental de votre activit\u00e9. Afin [&hellip;]<\/p>\n","protected":false},"author":72930,"featured_media":181245,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3897,13344],"tags":[],"class_list":["post-181244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-ressources-fr"],"_links":{"self":[{"href":"https:\/\/startup.info\/fr\/wp-json\/wp\/v2\/posts\/181244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/startup.info\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startup.info\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startup.info\/fr\/wp-json\/wp\/v2\/users\/72930"}],"replies":[{"embeddable":true,"href":"https:\/\/startup.info\/fr\/wp-json\/wp\/v2\/comments?post=181244"}],"version-history":[{"count":0,"href":"https:\/\/startup.info\/fr\/wp-json\/wp\/v2\/posts\/181244\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startup.info\/fr\/wp-json\/wp\/v2\/media\/181245"}],"wp:attachment":[{"href":"https:\/\/startup.info\/fr\/wp-json\/wp\/v2\/media?parent=181244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startup.info\/fr\/wp-json\/wp\/v2\/categories?post=181244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startup.info\/fr\/wp-json\/wp\/v2\/tags?post=181244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}